{"id":12,"count":1,"description":"","link":"https:\/\/demos.ascendoor.com\/republic-times-gadgets\/tag\/camera\/","name":"Camera","slug":"camera","taxonomy":"post_tag","meta":[],"_links":{"self":[{"href":"https:\/\/demos.ascendoor.com\/republic-times-gadgets\/wp-json\/wp\/v2\/tags\/12","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/demos.ascendoor.com\/republic-times-gadgets\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/demos.ascendoor.com\/republic-times-gadgets\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/demos.ascendoor.com\/republic-times-gadgets\/wp-json\/wp\/v2\/posts?tags=12"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}